{"id":763,"date":"2023-03-08T13:14:38","date_gmt":"2023-03-08T11:14:38","guid":{"rendered":"https:\/\/www.sterzelbacher.de\/wp\/?post_type=tribe_events&#038;p=763"},"modified":"2023-03-08T13:14:38","modified_gmt":"2023-03-08T11:14:38","slug":"katzenkopffest-in-koenigsberg","status":"publish","type":"tribe_events","link":"https:\/\/www.sterzelbacher.de\/wp\/event\/katzenkopffest-in-koenigsberg\/","title":{"rendered":"Katzenkopffest in K\u00f6nigsberg"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"tags":[],"tribe_events_cat":[7],"class_list":["post-763","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-auftritte","cat_auftritte"],"_links":{"self":[{"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/tribe_events\/763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/tribe_events\/763\/revisions"}],"predecessor-version":[{"id":764,"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/tribe_events\/763\/revisions\/764"}],"wp:attachment":[{"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/media?parent=763"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/tags?post=763"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.sterzelbacher.de\/wp\/wp-json\/wp\/v2\/tribe_events_cat?post=763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}